{"id":1697,"date":"2022-06-18T19:00:39","date_gmt":"2022-06-18T17:00:39","guid":{"rendered":"https:\/\/www.geldmeisterin.com\/index.php\/2022\/06\/18\/metaverse-die-wunderbare-welt-fuer-investoren\/"},"modified":"2022-06-18T19:00:39","modified_gmt":"2022-06-18T17:00:39","slug":"metaverse-die-wunderbare-welt-fuer-investoren","status":"publish","type":"post","link":"https:\/\/www.geldmeisterin.com\/index.php\/2022\/06\/18\/metaverse-die-wunderbare-welt-fuer-investoren\/","title":{"rendered":"Metaverse &#8211; die wunderbare Welt f\u00fcr Investoren?"},"content":{"rendered":"<p><iframe src=\"https:\/\/anchor.fm\/geldmeisterin\/embed\/episodes\/Metaverse---die-wunderbare-Welt-fr-Investoren-e1jco2n\" height=\"180px\" width=\"100%\" frameborder=\"0\" scrolling=\"no\" style=\"width:100%;height:180px\"><\/iframe><\/p>\n<p>Metaverse ist viel, viel mehr als Meta, ehemals Facebook, betont Anja Combrink-Birkholz von der Schweizer Investment Gruppe Lombard Odier (LOIM). Wir st\u00fcnden hier noch ganz am Anfang beim Aufbau einer virtuellen Welt, die zunehmend auch unsere reale Welt beeinflussen wird. Daher wei\u00df man auch noch nicht wirklich, wer die Big Player sein werden. Getrieben wird das Ganze nat\u00fcrlich von der Gaming-Branche. Bis der Megatrend wirklich zu einem wird, k\u00f6nnen Jahre vergehen. Um jetzt schon dabei zu sein k\u00f6nne man aber durchaus auf klassische Marken setzen, die in der virtuellen Welt schon einen Fu\u00df in der T\u00fcr haben, meint die LOIM-Expertin. Angefangen von den technischen Ausr\u00fcstern wie eine Microsoft oder Alphabet, \u00fcber Spielkonzerne wie Roblox, aber auch jene Mode- und Luxusmarken sind Meta-tauglich, die sich auch schon intensiv mit der virtuellen Welt als wichtige Werbeplattform f\u00fcr die realen Verk\u00e4ufe besch\u00e4ftigen.<\/p>\n<p>Als Kind des gekommen und gegangenen Hypes \u201eSecond Life\u201c bin ich da ein wenig skeptisch, ob Metaverse und das reale Leben wirklich einmal verschmelzen. Ich glaube, dass sehen Zuckerberg und Co. ein wenig durch die rosa Brille. Was daf\u00fcr spricht? H\u00f6rt Anja Combrink-Birkholz von Lombard Odier selbst.<\/p>\n<p>Viel H\u00f6rvergn\u00fcgen w\u00fcnschen die GELDMEISTERIN und Julia Kistner, die sich freuen w\u00fcrde, wenn ihr den Podcast GELDMEISTERIN liked, abonniert und weiterempfiehlt, damit die Anlage-Bewegung GELDMEISTERIN in Bewegung kommt.<\/p>\n<p>Rechtlicher Hinweis: Das sind keinesfalls Empfehlungen, sondern nur meine pers\u00f6nlichen Gedanken. Die Autorin \u00fcbernimmt keinerlei Haftung die daraus erw\u00e4chst, dass man entsprechend Ihrer Medienbeitr\u00e4ge Investments t\u00e4tigt.<\/p>\n<p>Musik- &amp; Soundrechte: https:\/\/www.geldmeisterin.com\/index.php\/musik-und-soundrechte\/<\/p>\n<p>#Metaverse #Megatrend #Aktien #Hype #LOIM #AnjaCombrink-Birkholz #GELDMEISTERIN #JuliaKistner #Investmentduell #Vorsorge #investment #podcast #Spekulation #B\u00f6rse #Zuckerberg #Meta #SecondLife #Microsoft #Alphabet #LombardOdier #virtualreality #gaming<\/p>\n<p>Foto: Pixabay<\/p>\n<p>&#8212; <\/p>\n<p>Send in a voice message: https:\/\/anchor.fm\/geldmeisterin\/message<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Metaverse ist viel, viel mehr als Meta, ehemals Facebook, betont Anja Combrink-Birkholz von der Schweizer Investment Gruppe Lombard Odier (LOIM). Wir st\u00fcnden hier noch ganz am Anfang beim Aufbau einer virtuellen Welt, die zunehmend auch unsere reale Welt beeinflussen wird. Daher wei\u00df man auch noch nicht wirklich, wer die Big Player sein werden. Getrieben wird [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1698,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1697","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hot","has-thumbnail"],"_links":{"self":[{"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/posts\/1697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/comments?post=1697"}],"version-history":[{"count":0,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/posts\/1697\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/media\/1698"}],"wp:attachment":[{"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/media?parent=1697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/categories?post=1697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.geldmeisterin.com\/index.php\/wp-json\/wp\/v2\/tags?post=1697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}